{"id":670,"date":"2018-12-21T16:54:28","date_gmt":"2018-12-21T16:54:28","guid":{"rendered":"http:\/\/inspirationdesurvie.net\/blog\/?p=670"},"modified":"2018-12-22T11:40:57","modified_gmt":"2018-12-22T11:40:57","slug":"solstice","status":"publish","type":"post","link":"https:\/\/inspirationdesurvie.net\/blog\/solstice\/","title":{"rendered":"Solstice"},"content":{"rendered":"\n<p>Le\njour se l\u00e8ve mollement sur la ville d\u00e9j\u00e0 r\u00e9veill\u00e9e. Il coule\ndans les rues de la cit\u00e9 o\u00f9 se presse d\u00e9j\u00e0 une foule fourmillante\nd&rsquo;enfants coinc\u00e9s dans des carapaces d&rsquo;adultes, en beaux habits de\ntravail. Ils pensent faire tourner le monde. Le monde, lui, s&rsquo;en\nbalance. Il tourne et tournera toujours, m\u00eame lorsque, en un\nbattement d&rsquo;\u00e8re, tous auront disparu. Et c&rsquo;est dans l&rsquo;indiff\u00e9rence\nmutuelle des h\u00e8res humains et du monde que la lumi\u00e8re froide pleut\nsur la ville.<\/p>\n\n\n\n<p>Dans\nun parc perdu, un homme est assis sur un banc, immobile au milieu des\ngrappes mouvantes de travailleurs. Lui, il\na regard\u00e9 le soleil se lever entre deux tours de verre, par-del\u00e0 la\nligne hach\u00e9e de\nl&rsquo;horizon. Il a fix\u00e9 l&rsquo;astre per\u00e7ant dans la brume du matin.\nPar la seule\nforce de son regard, la sph\u00e8re incandescente s\u2019est dress\u00e9e dans\nle ciel. Elle est sortie de la nuit pour\ntout \u00e9clairer. De\nsa chaleur, elle a fait fondre la fine pellicule de givre qu\u2019avait\n\u00e9crite la nuit. Une\nnouvelle page se tourne \u00e0 mesure que le jour avance.<\/p>\n\n\n\n<p>Entre\nl\u2019orbe p\u00e2le et la paire d\u2019yeux, un\nlien se cr\u00e9e, qui lie l\u2019un \u00e0 l\u2019autre, comme un c\u00e2ble invisible\net pourtant incroyablement solide. Ainsi tir\u00e9e, le navire de lumi\u00e8re\nglisse dans l\u2019azur. L\u2019homme n\u2019est pas le seul \u00e0 l\u2019appeler \u00e0\nlui. D\u2019autres font le m\u00eame travail, le tractant \u00e9galement \u00e0 eux.\nIl en va de m\u00eame dans d\u2019autres villes, dans d\u2019autres r\u00e9gions,\ndans d\u2019autres pays. Plus \u00e0 l\u2019Ouest, d\u00e9j\u00e0 des volont\u00e9s se\nr\u00e9veillent et scrutent la ligne d\u2019horizon et attirent de leurs\nv\u0153ux le soleil hi\u00e9mal.<\/p>\n\n\n\n<p>Et\n\u00e0 force d\u2019attraper la lueur de leurs\nregards, ils la tirent vers eux et la font aller plus haut\ndans le ciel et la font rester plus\nlongtemps dans les cieux. Le soleil est\ncomme ralenti par la puissance de ces esprits h\u00e9liotropes.<\/p>\n\n\n\n<p>Et\nplus il ralentit, ce soleil, plus les regards se tournent vers lui.\nEt ainsi, par effet boule de neige, le soleil r\u00e9chauffe le c\u0153ur de\nl\u2019hiver et apporte de nouveau une lumi\u00e8re bienvenue sur nos t\u00eates.<\/p>\n\n\n\n<p>L\u2019hiver\ncommence et, d\u00e9j\u00e0, il termine. Les jours s\u2019\u00e9tirent et sortent de\nleur torpeur. Le solstice est plein des promesses du printemps.<\/p>\n<p class=\"wp-flattr-button\"><a class=\"FlattrButton\" style=\"display:none;\" href=\"https:\/\/inspirationdesurvie.net\/blog\/solstice\/\" title=\" Solstice\" rev=\"flattr;uid:Alexis_Ids;language:fr_FR;category:text;tags:Hiver,Regard,Soleil,Solstice,Volont\u00e9,blog;popout:0;button:compact;\">Le jour se l\u00e8ve mollement sur la ville d\u00e9j\u00e0 r\u00e9veill\u00e9e. Il coule dans les rues de la cit\u00e9 o\u00f9 se presse d\u00e9j\u00e0 une foule fourmillante d&rsquo;enfants coinc\u00e9s dans des carapaces...<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Le jour se l\u00e8ve mollement sur la ville d\u00e9j\u00e0 r\u00e9veill\u00e9e. Il coule dans les rues de la cit\u00e9 o\u00f9 se presse d\u00e9j\u00e0 une foule fourmillante d&rsquo;enfants coinc\u00e9s dans des carapaces d&rsquo;adultes, en beaux habits de travail. Ils pensent faire tourner le monde. Le monde, lui, s&rsquo;en balance. Il tourne et tournera toujours, m\u00eame lorsque, en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[116,252,60,83,253],"class_list":["post-670","post","type-post","status-publish","format-standard","hentry","category-nouvelle","tag-hiver","tag-regard","tag-soleil","tag-solstice","tag-volonte"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s4m3os-solstice","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/670","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/comments?post=670"}],"version-history":[{"count":3,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/670\/revisions"}],"predecessor-version":[{"id":674,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/670\/revisions\/674"}],"wp:attachment":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/media?parent=670"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/categories?post=670"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/tags?post=670"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}