{"id":562,"date":"2015-10-08T10:06:44","date_gmt":"2015-10-08T10:06:44","guid":{"rendered":"http:\/\/inspirationdesurvie.net\/blog\/?p=562"},"modified":"2015-10-20T09:19:16","modified_gmt":"2015-10-20T09:19:16","slug":"derive-somatique","status":"publish","type":"post","link":"https:\/\/inspirationdesurvie.net\/blog\/derive-somatique\/","title":{"rendered":"D\u00e9rive somatique"},"content":{"rendered":"<div id=\"attachment_563\" style=\"width: 1034px\" class=\"wp-caption aligncenter\"><a href=\"https:\/\/inspirationdesurvie.net\/blog\/wp-content\/uploads\/2015\/10\/light_2_by_dejan91lp-d8tohv6.jpg\"><img loading=\"lazy\" decoding=\"async\" aria-describedby=\"caption-attachment-563\" class=\"size-full wp-image-563\" src=\"https:\/\/inspirationdesurvie.net\/blog\/wp-content\/uploads\/2015\/10\/light_2_by_dejan91lp-d8tohv6.jpg\" alt=\"CC-BY-SA dejan91lp\" width=\"1024\" height=\"768\" srcset=\"https:\/\/inspirationdesurvie.net\/blog\/wp-content\/uploads\/2015\/10\/light_2_by_dejan91lp-d8tohv6.jpg 1024w, https:\/\/inspirationdesurvie.net\/blog\/wp-content\/uploads\/2015\/10\/light_2_by_dejan91lp-d8tohv6-300x225.jpg 300w, https:\/\/inspirationdesurvie.net\/blog\/wp-content\/uploads\/2015\/10\/light_2_by_dejan91lp-d8tohv6-619x464.jpg 619w\" sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/a><p id=\"caption-attachment-563\" class=\"wp-caption-text\">CC-BY-SA dejan91lp<\/p><\/div>\n<p style=\"text-align: justify;\">Dix-sept heure cinquante-neuf. Il ne reste plus qu\u2019une minute \u00e0 attendre. Les aiguilles de l\u2019horloge s\u00e9parent le cadran en deux moiti\u00e9s identiques. Les portes sont ferm\u00e9es pendant que John sert le dernier client. Il lui jette \u00e0 la figure son dernier sourire de la journ\u00e9e ainsi qu\u2019un \u00ab au revoir \u00bb exp\u00e9ditif et le client s\u2019en va poursuivre sa soir\u00e9e dans un lieu plus plaisant que celui-ci. John n\u2019a plus qu\u2019\u00e0 compter sa caisse, maintenant. Bient\u00f4t, il pourra lui aussi quitter cette cage trop propre. Tandis que ses doigts glissent sur les billets sales et froiss\u00e9s, il esp\u00e8re secr\u00e8tement ne pas avoir de diff\u00e9rence de caisse. Cela le forcerait \u00e0 recompter et m\u00eame, dans le cas o\u00f9 sa caisse s\u2019obstinerait \u00e0 ne pas \u00eatre juste, il serait oblig\u00e9 \u00e0 donner des explications \u00e0 son chef. Ce n\u2019est pas que John se sente coupable de quelque crime. C\u2019est juste qu\u2019il n\u2019a pas envie de perdre du temps en d\u2019inutiles explications. Quand il compte les billets de cinquante euros, une pointe d\u2019anxi\u00e9t\u00e9 l\u2019assaille. L\u2019id\u00e9e de rester une seconde de plus que n\u00e9cessaire dans cet endroit trop blanc pour \u00eatre honn\u00eate lui est insupportable. En jetant un regard en coin aux parois immacul\u00e9es, il ne se souvient plus s\u2019il se trouve dans une prison, un h\u00f4pital ou quelque autre chambre o\u00f9 l\u2019on ne fait que des mauvaises rencontres. Il termine de compter les pi\u00e8ces d\u2019un centime et clique sur \u00ab valider \u00bb. Il y a une seconde de flottement durant laquelle son c\u0153ur arr\u00eate de battre. Heureusement, la caisse s\u2019av\u00e8re \u00eatre juste, ce soir. John respire avec satisfaction. Le voici libre de regagner ses p\u00e9nates.<!--more--><\/p>\n<p style=\"text-align: justify;\">En poussant un bref soupir de soulagement, John prend sa caisse sous le bras et la range dans le coffre. Il se saisit de son sac et de sa veste. En quelques minutes, il est dehors. Pour la premi\u00e8re fois depuis plus de huit heures, il voit \u00e0 quoi ressemble le ciel. Le monde ext\u00e9rieur n\u2019a pas tellement chang\u00e9 depuis ce matin. Il ferme les yeux et respire \u00e0 pleins poumons l\u2019air vici\u00e9 du centre-ville, faisant ainsi le plein d\u2019hydrocarbures. Fait \u00e9trange : son mal de cr\u00e2ne ne passe pas. Il fronce les sourcils. Cette migraine dure depuis plusieurs jours d\u00e9j\u00e0, comme un \u00e9tau qui ne se desserre pas. Il marche vite. La t\u00eate lui tourne comme s\u2019il \u00e9tait ivre. Il a du mal \u00e0 voir o\u00f9 il va. Il a l\u2019impression que toutes les rues de Bruxelles se ressemblent et se rassemblent pour le renvoyer dans sa prison. Il se d\u00e9p\u00eache de monter dans un tram qui passait par l\u00e0 avant que les murs ne murissent leur d\u00e9cision.<\/p>\n<p style=\"text-align: justify;\">Une fois rentr\u00e9 chez lui, John se vautre directement dans le fauteuil, comme si ses forces l\u2019avaient abandonn\u00e9. il reste ainsi de longues minutes sans bouger. Il reste amorphe, plong\u00e9 dans une contemplation absurde de la paroi blafarde qui se dresse devant lui depuis de nombreuses ann\u00e9es, sans pourtant jamais avoir chang\u00e9. Il cligne des yeux une fois. Une deuxi\u00e8me fois encore. Avant la troisi\u00e8me fois, son estomac se rappelle \u00e0 lui : il grogne, l\u2019inf\u00e2me. Il geint tellement fort que la t\u00eate finit par l\u2019\u00e9couter et met en branle pieds et mains. Avec des gestes lents, le propri\u00e9taire de toutes ces parties s\u2019extrait p\u00e9niblement du fauteuil. Il arrive \u00e0 se trainer jusqu\u2019\u00e0 l\u2019ordinateur. Il attend que celui-ci s\u2019allume sans que ses yeux ne trahissent le passage d\u2019aucune pens\u00e9e particuli\u00e8re. Apr\u00e8s quelques manipulations, il peut enfin passer commande d\u2019un repas. Ce sera indien, ce soir. Une joie indescriptible l\u2019envahit, mais encore une fois, son corps n\u2019en laisse rien paraitre.<\/p>\n<p style=\"text-align: justify;\">Dans une heure, le repas sera l\u00e0. En attendant que le livreur arrive, John remarque le casque qui se trouve \u00e0 port\u00e9e de sa main. Il lui reste au moins une heure \u00e0 attendre avant que l\u2019on sonne \u00e0 sa porte. Le verre semi-opaque lance des reflets argent\u00e9s qui lui font envie. Il n\u2019h\u00e9site pas plus d\u2019une seconde et se saisit de l\u2019objet aux formes \u00e9pur\u00e9es. Il branche le c\u00e2ble \u00e0 son ordinateur. D\u2019une main, il d\u00e9gage ses cheveux n\u00e9glig\u00e9s et de l\u2019autre, il pose le casque sur sa t\u00eate. Il rabat la visi\u00e8re sur ses yeux. Le programme est lanc\u00e9. Aussit\u00f4t, une lumi\u00e8re blanche remplit son champ de vision. Il n\u2019y a d\u2019ailleurs rien d\u2019autre que cette lumi\u00e8re, qui lui ravit les sens. De temps en temps, il y a une variation dans la couleur ou dans l\u2019intensit\u00e9, mais c\u2019est toujours la m\u00eame lumi\u00e8re qui lui lave les yeux et le cerveau de tout ce qu\u2019il a v\u00e9cu aujourd\u2019hui. De cette fa\u00e7on, il sera pr\u00eat \u00e0 supporter une nouvelle journ\u00e9e.<\/p>\n<p style=\"text-align: justify;\">Ce n\u2019est pas que ce qu\u2019il fasse soit p\u00e9nible ou stressant. Tout au contraire, le travail de John est inconsistant : tout au long du jour, il ins\u00e8re des chiffres et des lettres dans des formulaires, ce qu\u2019une machine pourrait faire mieux que lui. La seule plus-value dont il pourrait se vanter proviendrait des ventes qu\u2019il r\u00e9ussirait \u00e0 faire sur la journ\u00e9e. Mais pour \u00eatre honn\u00eate, il y en a tellement peu que son employeur ferait mieux de se d\u00e9cider \u00e0 le remplacer d\u00e9finitivement par une machine.<\/p>\n<p style=\"text-align: justify;\">Il y a bien des d\u00e9cennies, certaines personnes avaient pr\u00e9dit qu\u2019une fois le monde rempli de machines, l\u2019\u00eatre humain serait d\u00e9barrass\u00e9 de la contrainte du travail. John y pense parfois, quand il en a le temps, et se dit que l\u2019humanit\u00e9 a d\u00fb \u00e9chouer quelque part, puisqu\u2019il continue aujourd\u2019hui de s\u2019abrutir \u00e0 r\u00e9aliser des t\u00e2ches qu\u2019un ordinateur pourrait faire mieux que lui. Et ce sont les employ\u00e9s eux-m\u00eames qui s\u2019opposent \u00e0 cette \u00e9volution, pour le \u00ab droit au travail \u00bb. Au final, gr\u00e2ce \u00e0 l\u2019inertie des \u00eatres humains, les machines n\u2019auront apport\u00e9 que plus d\u2019ins\u00e9curit\u00e9. Parce que personne n\u2019a r\u00e9agi \u00e0 faire changer un mod\u00e8le vieux de deux si\u00e8cles, on emploie des \u00eatres humains comme des machines. Des milliers de personnes se retrouvent dans des emplois sans la moindre goutte de cr\u00e9ativit\u00e9, r\u00e9p\u00e9tant inlassablement les m\u00eames gestes, encore et encore, jusqu\u2019\u00e0 ce que vienne l\u2019\u00e2ge de la retraite.<\/p>\n<p style=\"text-align: justify;\">C\u2019est cela que John aimerait pouvoir formuler. Mais il n\u2019a pas le temps de dire quoi que ce soit la journ\u00e9e, et quand le soir est l\u00e0, il n\u2019en a plus la force. Apr\u00e8s avoir pass\u00e9 sa vie \u00e0 faire le travail d\u2019une machine, il se met lui aussi en veille, pour ne plus rien savoir de cette soci\u00e9t\u00e9 sans saveur. Il se fond alors dans la chaleur r\u00e9confortante et narcotique des lumi\u00e8res du r\u00e9seau qui le connecte au monde.<\/p>\n<p style=\"text-align: justify;\">Apr\u00e8s une heure de b\u00e9atitude, quelqu\u2019un sonne \u00e0 la porte de John, mais celui-ci ne l\u2019entend pas. Quelques minutes plus tard, son t\u00e9l\u00e9phone portable vibre dans son sac, mais sans plus attirer l\u2019attention de son propri\u00e9taire que la sonnette. L\u2019appartement pourrait \u00eatre vide, cela reviendrait au m\u00eame. \u00c0 proprement parler, il n\u2019y a d\u2019ailleurs aucun \u00eatre vivant entre ces murs froids qu\u2019\u00e9clairent une lumi\u00e8re sans chaleur. Finalement, les coups \u00e0 la porte cessent et le silence revient s\u2019installer en roi et maitre. La nuit tombe. Des dizaines de lumi\u00e8res identiques brillent aux fen\u00eatres des appartements de la ville. Comme un c\u0153ur qui palpite faiblement.<\/p>\n<p class=\"wp-flattr-button\"><a class=\"FlattrButton\" style=\"display:none;\" href=\"https:\/\/inspirationdesurvie.net\/blog\/derive-somatique\/\" title=\" D\u00e9rive somatique\" rev=\"flattr;uid:Alexis_Ids;language:fr_FR;category:text;tags:Ali\u00e9nation,Lumi\u00e8re,Travail,Virtuel,blog;popout:0;button:compact;\">Dix-sept heure cinquante-neuf. Il ne reste plus qu\u2019une minute \u00e0 attendre. Les aiguilles de l\u2019horloge s\u00e9parent le cadran en deux moiti\u00e9s identiques. Les portes sont ferm\u00e9es pendant que John sert...<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Dix-sept heure cinquante-neuf. Il ne reste plus qu\u2019une minute \u00e0 attendre. Les aiguilles de l\u2019horloge s\u00e9parent le cadran en deux moiti\u00e9s identiques. Les portes sont ferm\u00e9es pendant que John sert le dernier client. Il lui jette \u00e0 la figure son dernier sourire de la journ\u00e9e ainsi qu\u2019un \u00ab au revoir \u00bb exp\u00e9ditif et le client [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[4],"tags":[235,231,89,236],"class_list":["post-562","post","type-post","status-publish","format-standard","hentry","category-nouvelle","tag-alienation","tag-lumiere","tag-travail","tag-virtuel"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4m3os-94","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/562","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/comments?post=562"}],"version-history":[{"count":4,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/562\/revisions"}],"predecessor-version":[{"id":570,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/562\/revisions\/570"}],"wp:attachment":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/media?parent=562"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/categories?post=562"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/tags?post=562"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}