{"id":355,"date":"2014-03-21T10:02:48","date_gmt":"2014-03-21T10:02:48","guid":{"rendered":"http:\/\/inspirationdesurvie.net\/blog\/?p=355"},"modified":"2015-08-23T12:30:10","modified_gmt":"2015-08-23T12:30:10","slug":"supplique-printaniere","status":"publish","type":"post","link":"https:\/\/inspirationdesurvie.net\/blog\/supplique-printaniere\/","title":{"rendered":"Supplique printani\u00e8re"},"content":{"rendered":"<p style=\"text-align: justify;\">Oh\u00a0! je t&rsquo;en supplie, n&rsquo;oublie pas de rire\u00a0!<br \/>\nJe sais que ce n&rsquo;est pas toujours facile et que le monde ne s&rsquo;y pr\u00eate gu\u00e8re. Parfois, c&rsquo;est bien normal, on aurait envie de baisser les armes. Je sais toutes les horreurs de la Terre. On voudrait se laisser aller aux larmes. On voudrait laisser la tristesse envahir notre \u00e2me, qu&rsquo;elle nous inonde et \u00e9teigne toute flamme. Heureusement, il survit toujours une \u00e9tincelle.<!--more--><\/p>\n<p style=\"text-align: justify;\">Je t&rsquo;en supplie, n&rsquo;oublie pas de rire.<br \/>\nTu as tellement de raisons d&rsquo;\u00eatre heureuse, tu sais\u00a0? Le monde n&rsquo;est pas parfait, loin de l\u00e0, mais regarde donc par ta fen\u00eatre et vois le printemps qui revient enfin. Ne ressens-tu pas les \u00e9chos de cette Nature qui se r\u00e9veille de son long sommeil\u00a0? Si par malheur tu ne trouves rien en toi qui vaille la peine de se r\u00e9jouir, puise dans ce spectacle mill\u00e9naire la force de sourire. Laisse-toi aller \u00e0 ce d\u00e9bordement de vie et accompagne de tes \u00e9clats de bonheur ce rouge-gorge qui se cache dans le bourgeonnement des buissons pour chanter quelques notes envol\u00e9es.<\/p>\n<p style=\"text-align: justify;\">Je t&rsquo;en supplie, n&rsquo;oublie jamais de rire.<br \/>\nCar si les moments pr\u00e9sents peuvent \u00eatre parfois tristes, tu peux te raccrocher au pass\u00e9 ou au futur. La vie, c&rsquo;est tellement plus que ces quelques secondes qui filent sous tes doigts. C&rsquo;est un fleuve qui s&rsquo;\u00e9coule, sans cesse changeant, disait ce philosophe. Plonge-toi donc dans le torrent de ces souvenirs heureux qui faisaient que tu te sentais si vivante, lorsque le soleil d&rsquo;\u00e9t\u00e9 r\u00e9chauffait nos c\u0153urs. Souviens-toi qu&rsquo;il brille toujours, ce disque de lumi\u00e8re, m\u00eame lorsqu&rsquo;il est voil\u00e9 par les nuages. Et souviens-toi que les nuages finissent par passer, m\u00eame ceux qui laissent une ombre froide sur les plaines.<\/p>\n<p style=\"text-align: justify;\">Je t&rsquo;en supplie, m\u00eame dans la nuit la plus noire, n&rsquo;oublie pas de rire.<br \/>\nN&rsquo;oublie jamais de rire d\u00e8s que tu le peux. Il ne faut pas perdre la moindre occasion. La vie passe si vite. En une minute, en une seconde, elle a fil\u00e9, sans que l&rsquo;on s&rsquo;en aper\u00e7oive. Il n&rsquo;en restera rien d&rsquo;autre que ce rire qui un jour aura retenti \u00e0 mes oreilles, comme un cristal qui tinte sans s&rsquo;arr\u00eater. Ah\u00a0! s&rsquo;il devait rester une seule chose, lorsque l&rsquo;univers s&rsquo;\u00e9croulera sur lui-m\u00eame, je veux que ce soit cela\u00a0: ton rire si doux dans lequel tout dispara\u00eetra.<\/p>\n<p style=\"text-align: justify;\">Je t&rsquo;en supplie, ma belle, n&rsquo;oublie pas de rire.<br \/>\nJe pourrais vivre des ann\u00e9es en m&rsquo;abreuvant seulement \u00e0 la source de ton rire. J&rsquo;aimerais tellement m&rsquo;en faire une couverture dans laquelle je pourrais m&rsquo;endormir sans penser \u00e0 rien d&rsquo;autre qu&rsquo;\u00e0 cette musique qui va de ta bouche \u00e0 mes oreilles. Tu es si belle, lorsque tu ris, que l&rsquo;on ferait tout pour que jamais tu ne t&rsquo;arr\u00eates, que jamais tu n&rsquo;aies \u00e0 pleurer. Tu es si belle lorsque tu ris qu&rsquo;on sentirait presque le monde basculer.<\/p>\n<p style=\"text-align: justify;\">Oh\u00a0! n&rsquo;oublie pas de rire.<br \/>\nEt si ce n&rsquo;est pas pour toi, sois pour moi l&rsquo;espace d&rsquo;un instant l&rsquo;enfant que tu sais si bien \u00eatre. Je te le demande \u00e9go\u00efstement. Ris-toi du monde. Vas-y, souris devant toutes ces petites merveilles du quotidien. Puisqu&rsquo;il te faut un pr\u00e9texte, pense \u00e0 tous ceux qui t&rsquo;aiment et qui sont l\u00e0 pour toi. Pense \u00e0 tout le bien que tu leur feras en te jouant ainsi de tes pens\u00e9es sombres. Pense \u00e0 cette chaleur qui \u00e9mane de tout ton \u00eatre lorsque tu ris. R\u00e9chauffe de ces quelques notes ceux qui tiennent \u00e0 toi.<\/p>\n<p style=\"text-align: justify;\">N&rsquo;oublie pas de rire.<br \/>\nFais entendre ton rire au monde entier. M\u00eame loin, je sais que je l&rsquo;entendrai. S&rsquo;il te plait, fais entendre \u00e0 tous ceux-l\u00e0 les doux arp\u00e8ges de ta joie. Illumine-les cette m\u00e9lodie \u00e9gren\u00e9e dans le silence de leurs vies.<\/p>\n<p class=\"wp-flattr-button\"><a class=\"FlattrButton\" style=\"display:none;\" href=\"https:\/\/inspirationdesurvie.net\/blog\/supplique-printaniere\/\" title=\" Supplique printani\u00e8re\" rev=\"flattr;uid:Alexis_Ids;language:fr_FR;category:text;tags:Printemps,Rire,Soleil,blog;popout:0;button:compact;\">Oh\u00a0! je t&rsquo;en supplie, n&rsquo;oublie pas de rire\u00a0! Je sais que ce n&rsquo;est pas toujours facile et que le monde ne s&rsquo;y pr\u00eate gu\u00e8re. Parfois, c&rsquo;est bien normal, on aurait...<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Oh\u00a0! je t&rsquo;en supplie, n&rsquo;oublie pas de rire\u00a0! Je sais que ce n&rsquo;est pas toujours facile et que le monde ne s&rsquo;y pr\u00eate gu\u00e8re. Parfois, c&rsquo;est bien normal, on aurait envie de baisser les armes. Je sais toutes les horreurs de la Terre. On voudrait se laisser aller aux larmes. On voudrait laisser la tristesse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":true,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[28,171,60],"class_list":["post-355","post","type-post","status-publish","format-standard","hentry","category-prose","tag-printemps","tag-rire","tag-soleil"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4m3os-5J","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/355","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/comments?post=355"}],"version-history":[{"count":4,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/355\/revisions"}],"predecessor-version":[{"id":499,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/355\/revisions\/499"}],"wp:attachment":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/media?parent=355"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/categories?post=355"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/tags?post=355"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}