{"id":31,"date":"2011-08-13T21:37:50","date_gmt":"2011-08-13T21:37:50","guid":{"rendered":"http:\/\/alexis.nuagedstete.com\/blog\/?p=31"},"modified":"2012-03-11T16:00:35","modified_gmt":"2012-03-11T16:00:35","slug":"lunaire-octe","status":"publish","type":"post","link":"https:\/\/inspirationdesurvie.net\/blog\/lunaire-octe\/","title":{"rendered":"Lunaire Octe"},"content":{"rendered":"<p>Par la fen\u00eatre ouverte, il y a le matin.<br \/>\nUne \u00e9paisse clart\u00e9 s&rsquo;insinue dans ma chambre.<br \/>\nDehors, des bruits d&rsquo;enfants, de moteurs et d&rsquo;oiseaux.<br \/>\nJe me r\u00e9veille enfin. Un nouveau jour commence.<\/p>\n<p>Par la fen\u00eatre ouverte, un disque d&rsquo;argent plein<br \/>\nM&rsquo;observe encore un peu. Je tire sur mes membres<br \/>\nQui, un \u00e0 un, craquent. Je gagne mon bureau<br \/>\nEt je pose mon cul. Le travail m&rsquo;est souffrance.<\/p>\n<p>Par la fen\u00eatre ouverte, un orage, hautain.<br \/>\nMe cache la lune, crache comme en novembre.<br \/>\nDans un rideau de pluie, il d\u00e9verse son eau<br \/>\nQui tombe sur les toits, percute le silence.<\/p>\n<p>Par la fen\u00eatre ouverte, un tissu de satin,<br \/>\nOuvrage arachn\u00e9en, tremble, ploie et se cambre.<br \/>\nLes fils de soie retiennent la lumi\u00e8re d&rsquo;en haut,<br \/>\nNe laissant plus passer que le soleil, immense.<\/p>\n<p>Par la fen\u00eatre ouverte, une cloche m&rsquo;atteint :<br \/>\nIl est d\u00e9j\u00e0 bien tard. Tout seul, je me remembre<br \/>\nQuelques \u00e9v\u00e9nements, des actes et des mots,<br \/>\nQuand soudain je revois le globe de fa\u00efence.<\/p>\n<p>Par la fen\u00eatre ouverte, un z\u00e9phyr me parvient,<br \/>\nJe tourne en rond, j&rsquo;attends. Je suis dans l&rsquo;antichambre<br \/>\nEt je me pr\u00e9pare tant que je peux, sans trop.<br \/>\nSouvent je m&rsquo;arr\u00eate, je me l\u00e8ve et m&rsquo;\u00e9lance.<\/p>\n<p>La fen\u00eatre se ferme et la lune s&rsquo;\u00e9teint<br \/>\nTandis que s&rsquo;allument les salons et les chambres.<br \/>\nLes heures vont sur moi en me courbant le dos.<br \/>\nDevant mes yeux tremblants, le monde entier danse.<\/p>\n<p>La fen\u00eatre est ferm\u00e9e d\u00e8s que la nuit me vient.<br \/>\nCe n&rsquo;est pas aujourd&rsquo;hui que je saisirai l&rsquo;ambre<br \/>\nQui flotte dans les cieux. Je passe mon temps \u2026 oh !<br \/>\n\u00c0 presque rien faire. Parfois, c&rsquo;est vrai, je pense.<\/p>\n<p class=\"wp-flattr-button\"><a class=\"FlattrButton\" style=\"display:none;\" href=\"https:\/\/inspirationdesurvie.net\/blog\/lunaire-octe\/\" title=\" Lunaire Octe\" rev=\"flattr;uid:Alexis_Ids;language:fr_FR;category:text;tags:Alexandrins,Fen\u00eatre,Lune,blog;popout:0;button:compact;\">Par la fen\u00eatre ouverte, il y a le matin. Une \u00e9paisse clart\u00e9 s&rsquo;insinue dans ma chambre. Dehors, des bruits d&rsquo;enfants, de moteurs et d&rsquo;oiseaux. Je me r\u00e9veille enfin. Un nouveau...<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Par la fen\u00eatre ouverte, il y a le matin. Une \u00e9paisse clart\u00e9 s&rsquo;insinue dans ma chambre. Dehors, des bruits d&rsquo;enfants, de moteurs et d&rsquo;oiseaux. Je me r\u00e9veille enfin. Un nouveau jour commence. Par la fen\u00eatre ouverte, un disque d&rsquo;argent plein M&rsquo;observe encore un peu. Je tire sur mes membres Qui, un \u00e0 un, craquent. Je [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[11,10],"tags":[13,15,12],"class_list":["post-31","post","type-post","status-publish","format-standard","hentry","category-lunaire","category-poesie","tag-alexandrins","tag-fenetre","tag-lune"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/p4m3os-v","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/31","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/comments?post=31"}],"version-history":[{"count":1,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/31\/revisions"}],"predecessor-version":[{"id":32,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/31\/revisions\/32"}],"wp:attachment":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/media?parent=31"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/categories?post=31"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/tags?post=31"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}