{"id":130,"date":"2012-05-14T23:28:45","date_gmt":"2012-05-14T23:28:45","guid":{"rendered":"http:\/\/inspirationdesurvie.net\/blog\/?p=130"},"modified":"2015-08-23T12:53:46","modified_gmt":"2015-08-23T12:53:46","slug":"agrume","status":"publish","type":"post","link":"https:\/\/inspirationdesurvie.net\/blog\/agrume\/","title":{"rendered":"Agrume"},"content":{"rendered":"<p style=\"text-align: justify;\">Tous les jours, on remettait au prisonnier \u00c1lamo l&rsquo;orange que lui apportait sa s\u0153ur. Depuis des ann\u00e9es, elle accomplissait ce petit rituel avant d&rsquo;aller travailler en ville. Lui, il gardait l&rsquo;agrume \u00e0 l&rsquo;ombre fraiche de sa cellule jusqu&rsquo;\u00e0 ce que le soleil atteigne son z\u00e9nith. \u00c0 ce moment seulement, il la pelait pour ensuite en d\u00e9guster la chair et le jus dont il ne perdait pas une goutte. C&rsquo;\u00e9taient les meilleures oranges de la r\u00e9gion.<br \/>\nLe reste de sa journ\u00e9e, il le passait \u00e0 observer les all\u00e9es et venues des citoyens libres. La prison se trouvait l\u00e9g\u00e8rement en surplomb et dominait une partie de la cit\u00e9 grouillante. Tout le jour, il sculptait dans du bois d&rsquo;oranger des chevaux ail\u00e9s qui suffisaient \u00e0 payer la nourriture qu&rsquo;on lui servait. Il y travaillait jusqu&rsquo;\u00e0 ce que la chaleur moite des rayons du soleil couchant le cloue \u00e0 terre. Alors, c&rsquo;\u00e9tait le moment pour lui de rejoindre la chorale avec sa voix de basse aux accents indig\u00e8nes.<br \/>\nAinsi allait la vie de condamn\u00e9. Une vie pas pire qu&rsquo;une autre, \u00e0 bien y r\u00e9fl\u00e9chir. Ce qui manquait le plus au prisonnier \u00c1lamo, c&rsquo;\u00e9taient les balades dans les for\u00eats, pieds nus sur le sol humide de pluies d&rsquo;\u00e9t\u00e9. Depuis de nombreuses saisons, il devait se contenter de l&rsquo;odeur des gouttes sur les mousses gorg\u00e9es de soleil. Dans ces moments-l\u00e0, un sentiment de nostalgie se saisissait de lui.<!--more--><\/p>\n<p style=\"text-align: justify;\">Le c\u0153ur de cette histoire d\u00e9bute avec le transfert d&rsquo;\u00c1lamo dans une cellule qui donnait directement sur la rue. Prisonnier mod\u00e8le, n&rsquo;ayant jamais tent\u00e9 de se soustraire \u00e0 sa condition, acceptant avec une r\u00e9signation exemplaire sa peine, il b\u00e9n\u00e9ficiait de quelque attention bienveillante des ge\u00f4liers. Il disposait dor\u00e9navant d&rsquo;un couteau aiguis\u00e9 pour travailler le bois. Il \u00e9tait presque heureux. M\u00eame les jours de pluie lui devenaient plus supportables.<br \/>\nUn jour, au matin d&rsquo;une pluie particuli\u00e8rement agr\u00e9able, sa s\u0153ur laissa un agrume diff\u00e9rent. Il n&rsquo;y avait plus d&rsquo;oranges dans tout le pays : on les revendait neuf fois plus ch\u00e8res aux Europ\u00e9ens qui en \u00e9taient friands et en faisaient des jus. On lui remit le fruit. La pluie tomba. Il ne r\u00e9sista pas et s&rsquo;\u00e9vada. Gr\u00e2ce \u00e0 cette lime apport\u00e9e par sa s\u0153ur.<\/p>\n<p class=\"wp-flattr-button\"><a class=\"FlattrButton\" style=\"display:none;\" href=\"https:\/\/inspirationdesurvie.net\/blog\/agrume\/\" title=\" Agrume\" rev=\"flattr;uid:Alexis_Ids;language:fr_FR;category:text;tags:Agrume,Citron,Orange,Peuplier,Prisonnier,blog;popout:0;button:compact;\">Tous les jours, on remettait au prisonnier \u00c1lamo l&rsquo;orange que lui apportait sa s\u0153ur. Depuis des ann\u00e9es, elle accomplissait ce petit rituel avant d&rsquo;aller travailler en ville. Lui, il gardait...<\/a><\/p>","protected":false},"excerpt":{"rendered":"<p>Tous les jours, on remettait au prisonnier \u00c1lamo l&rsquo;orange que lui apportait sa s\u0153ur. Depuis des ann\u00e9es, elle accomplissait ce petit rituel avant d&rsquo;aller travailler en ville. Lui, il gardait l&rsquo;agrume \u00e0 l&rsquo;ombre fraiche de sa cellule jusqu&rsquo;\u00e0 ce que le soleil atteigne son z\u00e9nith. \u00c0 ce moment seulement, il la pelait pour ensuite en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_publicize_message":"","jetpack_publicize_feature_enabled":true,"jetpack_social_post_already_shared":false,"jetpack_social_options":{"image_generator_settings":{"template":"highway","enabled":false},"version":2}},"categories":[3],"tags":[64,46,65,66,63],"class_list":["post-130","post","type-post","status-publish","format-standard","hentry","category-prose","tag-agrume","tag-citron","tag-orange","tag-peuplier","tag-prisonnier"],"jetpack_publicize_connections":[],"jetpack_featured_media_url":"","jetpack_shortlink":"https:\/\/wp.me\/s4m3os-agrume","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/comments?post=130"}],"version-history":[{"count":8,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/130\/revisions"}],"predecessor-version":[{"id":524,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/posts\/130\/revisions\/524"}],"wp:attachment":[{"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/media?parent=130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/categories?post=130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/inspirationdesurvie.net\/blog\/wp-json\/wp\/v2\/tags?post=130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}